{"id":1788,"date":"2020-05-22T20:15:09","date_gmt":"2020-05-22T20:15:09","guid":{"rendered":"https:\/\/fraeulein-lenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618.jpg"},"modified":"2020-05-22T20:15:09","modified_gmt":"2020-05-22T20:15:09","slug":"img_7618","status":"inherit","type":"attachment","link":"https:\/\/www.fraulenz.de\/en\/img_7618\/","title":{"rendered":"IMG_7618"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1788","attachment","type-attachment","status-inherit","hentry","post-preview"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IMG_7618 - Frau Lenz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IMG_7618 - Frau Lenz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Frau Lenz\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraulenz.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/IMG_7618-scaled.jpg\",\"url\":\"https:\\\/\\\/www.fraulenz.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/IMG_7618-scaled.jpg\",\"name\":\"IMG_7618 - Frau Lenz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraulenz.de\\\/#website\"},\"datePublished\":\"2020-05-22T20:15:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraulenz.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/IMG_7618-scaled.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraulenz.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/IMG_7618-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraulenz.de\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/IMG_7618-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.fraulenz.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IMG_7618\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraulenz.de\\\/#website\",\"url\":\"https:\\\/\\\/www.fraulenz.de\\\/\",\"name\":\"Frau Lenz\",\"description\":\"Gem\u00fcse aus dem Donnersbergkreis\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fraulenz.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraulenz.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fraulenz.de\\\/#organization\",\"name\":\"Frau Lenz\",\"url\":\"https:\\\/\\\/www.fraulenz.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fraulenz.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fraulenz.de\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-FrauLenz.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fraulenz.de\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Logo-FrauLenz.jpg\",\"width\":334,\"height\":266,\"caption\":\"Frau Lenz\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraulenz.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IMG_7618 - Frau Lenz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg","og_locale":"en_US","og_type":"article","og_title":"IMG_7618 - Frau Lenz","og_url":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg","og_site_name":"Frau Lenz","og_image":[{"width":1920,"height":2560,"url":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg","url":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg","name":"IMG_7618 - Frau Lenz","isPartOf":{"@id":"https:\/\/www.fraulenz.de\/#website"},"datePublished":"2020-05-22T20:15:09+00:00","breadcrumb":{"@id":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.fraulenz.de\/"},{"@type":"ListItem","position":2,"name":"IMG_7618"}]},{"@type":"WebSite","@id":"https:\/\/www.fraulenz.de\/#website","url":"https:\/\/www.fraulenz.de\/","name":"Frau Lenz","description":"Gem\u00fcse aus dem Donnersbergkreis","publisher":{"@id":"https:\/\/www.fraulenz.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraulenz.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fraulenz.de\/#organization","name":"Frau Lenz","url":"https:\/\/www.fraulenz.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fraulenz.de\/#\/schema\/logo\/image\/","url":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2026\/01\/Logo-FrauLenz.jpg","contentUrl":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2026\/01\/Logo-FrauLenz.jpg","width":334,"height":266,"caption":"Frau Lenz"},"image":{"@id":"https:\/\/www.fraulenz.de\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-225x300.jpg 225w, https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-1152x1536.jpg 1152w, https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-1536x2048.jpg 1536w, https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":2560,"file":"2020\/05\/IMG_7618-scaled.jpg","sizes":{"medium":{"file":"IMG_7618-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-225x300.jpg"},"thumbnail":{"file":"IMG_7618-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-150x150.jpg"},"1536x1536":{"file":"IMG_7618-1152x1536.jpg","width":1152,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-1152x1536.jpg"},"2048x2048":{"file":"IMG_7618-1536x2048.jpg","width":1536,"height":2048,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-1536x2048.jpg"},"full":{"file":"IMG_7618-scaled.jpg","width":1920,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"iPhone 6s Plus","caption":"","created_timestamp":"1589921782","copyright":"","focal_length":"4.15","iso":"64","shutter_speed":"0.058823529411765","title":"","orientation":1,"keywords":[]},"original_image":"IMG_7618.jpg"},"post":null,"source_url":"https:\/\/www.fraulenz.de\/wp-content\/uploads\/2020\/05\/IMG_7618-scaled.jpg","filename":"IMG_7618.jpg","filesize":3004818,"_links":{"self":[{"href":"https:\/\/www.fraulenz.de\/en\/wp-json\/wp\/v2\/media\/1788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraulenz.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.fraulenz.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraulenz.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraulenz.de\/en\/wp-json\/wp\/v2\/comments?post=1788"}]}}